{"id":684,"date":"2024-02-12T09:09:15","date_gmt":"2024-02-12T09:09:15","guid":{"rendered":"https:\/\/matteo.bz.it\/services\/reiki\/"},"modified":"2026-03-23T09:46:10","modified_gmt":"2026-03-23T09:46:10","slug":"reiki","status":"publish","type":"cpt_services","link":"https:\/\/matteo.bz.it\/de\/services\/reiki\/","title":{"rendered":"Energiebehandlungen"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\" style=\"font-size:15px\">Auf meinem Weg als ganzheitlicher Therapeut war ich schon fr\u00fch von der <strong>Welt der Energien<\/strong> fasziniert. Dieses tiefe Interesse hat mich dazu bewogen, alte Heiltechniken zu studieren und zu vertiefen \u2013 darunter <strong>Reiki, Pranotherapie<\/strong>, das Lesen der <strong>Akasha-Chronik<\/strong> sowie die A<strong>rbeit mit geistigen Ebenen<\/strong> und <strong>spirituellen F\u00fchrern<\/strong>. W\u00e4hrend meiner langj\u00e4hrigen Ausbildung habe ich erfahren, wie sehr unser Energiefeld den physischen K\u00f6rper, unsere Entscheidungen und die Ereignisse in unserem Leben beeinflusst. Es offenbarte sich mir eine tiefe Verbindung zwischen unserer inneren Welt und der \u00e4u\u00dferen Realit\u00e4t. &nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:15px\">Die vorgeschlagene Energiebehandlung findet in einer ruhigen und friedlichen Umgebung statt. Der Empf\u00e4nger liegt vollst\u00e4ndig bekleidet bequem auf einer Liege. Der Behandler legt seine H\u00e4nde sanft auf bestimmte Punkte des K\u00f6rpers, um den Energiefluss wieder ins Gleichgewicht zu bringen und eine tiefe Harmonisierung der Lebensenergie zu f\u00f6rdern.<br>Diese Behandlung hat zahlreiche Vorteile, darunter vor allem: <strong>tiefe Entspannung und Stressabbau, Beseitigung emotionaler Blockaden, gesteigertes Bewusstsein und eine St\u00e4rkung der Verbindung zum eigenen Inneren, was zu einem Gef\u00fchl des Wohlbefindens und zu dauerhaftem Gleichgewicht f\u00fchrt.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Eine Umarmung voller heilender Energie, die dir Harmonie und Gelassenheit schenkt<\/p>\n","protected":false},"author":2,"featured_media":619,"comment_status":"open","ping_status":"closed","template":"","cpt_services_group":[],"class_list":["post-684","cpt_services","type-cpt_services","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/matteo.bz.it\/de\/wp-json\/wp\/v2\/cpt_services\/684","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/matteo.bz.it\/de\/wp-json\/wp\/v2\/cpt_services"}],"about":[{"href":"https:\/\/matteo.bz.it\/de\/wp-json\/wp\/v2\/types\/cpt_services"}],"author":[{"embeddable":true,"href":"https:\/\/matteo.bz.it\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/matteo.bz.it\/de\/wp-json\/wp\/v2\/comments?post=684"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/matteo.bz.it\/de\/wp-json\/wp\/v2\/media\/619"}],"wp:attachment":[{"href":"https:\/\/matteo.bz.it\/de\/wp-json\/wp\/v2\/media?parent=684"}],"wp:term":[{"taxonomy":"cpt_services_group","embeddable":true,"href":"https:\/\/matteo.bz.it\/de\/wp-json\/wp\/v2\/cpt_services_group?post=684"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}